{"id":1240,"date":"2008-08-09T20:33:48","date_gmt":"2008-08-09T18:33:48","guid":{"rendered":"http:\/\/www.danielgrosse.com\/blog\/?p=1240"},"modified":"2013-08-14T16:30:07","modified_gmt":"2013-08-14T14:30:07","slug":"deutsch-amerikanische-trauung","status":"publish","type":"post","link":"https:\/\/www.danielgrosse.com\/blog\/deutsch-amerikanische-trauung\/","title":{"rendered":"Deutsch-amerikanische&nbsp;Trauung"},"content":{"rendered":"\n<!-- google_ad_section_start -->\n<p>Taucha. Sieben Eheschlie&#223;ungen fanden gestern am bei Paaren offenbar beliebten magischen Datum, dem 8.8.08, statt. Jede war auf ihre Weise etwas Besonderes, dennoch stach eine heraus. Denn mit der Hochzeit von Kristie und Tom D&#246;hler aus Leipzig wurden eine Amerikanerin und ein Deutscher amtlich zu Mann und Frau erkl&#228;rt.<\/p>\n<p>Uta Schneider vom Tauchaer Standesamt war schon seit Tagen aufgeregt, musste sie ihre Rede doch angesichts von etwa 25 amerikanischen G&#228;sten zweisprachig abhalten. Dazu &#252;bersetzte eine Dolmetscherin die Ansprache ins Italienische, da auch aus diesem Land Besuch anreiste. Und: Am Rathaus h&#228;ngte die Stadtverwaltung ein \u201eWelcome-Banner\u201c und die Flaggen von Deutschland und den USA auf. \u201eIst doch klar, dass wir da unkompliziert sind, wann hat man das schon in Taucha\u201c, meinte B&#252;rgermeister Holger Schirmbeck.<br \/>\n <br \/>\nSo ungew&#246;hnlich die Hochzeit, so verr&#252;ckt war auch das Kennenlernen der beiden 31-J&#228;hrigen. Kristie stammt aus Louisiana, ist nach Aussagen der Familie sehr reiselustig und kam 2003 nach Deutschland. Die Lehrerin sollte in Leipzig einer Gruppe von Computerfachleuten Nachhilfe in Englisch geben. Unter ihnen auch Tom, der in der Messestadt f&#252;r eine Firma arbeitet, die Navigationsger&#228;te-Software programmiert. Und offenbar brauchte Tom mehr Lektionen als seine Kollegen \u2013 Kristie entschloss sich, bei ihm in Leipzig zu bleiben. \u201eJa, Kristie war mal meine Lehrerin, heute lernen wir aber ganz gut voneinander\u201c, scherzte Tom D&#246;hler.<\/p>\n<p>Nach der Trauung kam das, was die amerikanischen G&#228;ste nicht kannten: Das Zers&#228;gen des Baumstammes. \u201eWas passiert jetzt?\u201c, fragten die T&#246;chter von Marian Lormand, der Schw&#228;gerin der Braut. \u201eOh, ich wei&#223; nicht, es ist sicher eine deutsche Tradition, schaut es euch an\u201c, riet sie und wurde prompt von der deutschen Verwandtschaft aufgekl&#228;rt, dass es sich um den beliebtesten Brauch handelt, bei dem das Paar beweisen muss, auch sp&#228;ter prima zusammenarbeiten zu k&#246;nnen. Das funktionierte vor dem Rathaus soweit ganz gut. Bis zu der Stelle, an der ein Nagel die S&#228;ge aufhielt. Aber auch das meisterte das Paar. Ein Familienangeh&#246;riger holte eine Zange, ein anderer brachte gar ein zweites S&#228;geblatt. \u201eIn den USA wird die Braut wie eine Prinzessin behandelt, und hier muss sie hart arbeiten\u201c, wunderte sich Marian Lormand. Was Kristie aber nichts ausmachte, sie lachte unentwegt. Unter dem Johlen und Klatschen der G&#228;ste schafften die frisch Verm&#228;hlten die letzten Zentimeter und konnten sich danach nicht einmal in die Arme fallen. \u201eIch hab mich geschnitten, muss das erstmal abwaschen\u201c, zeigte der Br&#228;utigam auf einen Finger der rechten Hand. Nachgeholt wurde das K&#252;sschen, nachdem das Paar aus einem riesigen Bettlaken per Schere ein gro&#223;es Herz ausgeschnitten hatte und der Ehemann seine Auserw&#228;hlte durch die so entstandene symboltr&#228;chtige &#214;ffnung trug.<\/p>\n<p>Gefeiert wurde in der Kulturscheune des Tauchaer Schlosses. Am Abend erhellte dann ein rund zehnmin&#252;tiges Feuerwerk den Himmel &#252;ber dem historischen Hof und der Stadt. Die amerikanische Familie der Braut bleibt noch einige Tage in Taucha und Leipzig. Eineinhalb Wochen dauert ihr Aufenthalt, unter anderem haben die US-B&#252;rger, von denen die meisten zum ersten Mal in Deutschland sind, schon Dresden, Berlin und Potsdam gesehen. <\/p>\n<p>Dass der 8.8. bei Paaren so beliebt war, liegt sicher auch an der Bedeutung der Zahl, die f&#252;r Unsterblichkeit und Unendlichkeit steht. <\/p>\n<p><em>Geschrieben f&#252;r die Leipziger Volkszeitung, erschienen am 9. August 2008.<\/em><\/p>\n<div id=\"facebook_like\"><iframe src=\"http:\/\/www.facebook.com\/plugins\/like.php?href=https%3A%2F%2Fwww.danielgrosse.com%2Fblog%2Fdeutsch-amerikanische-trauung%2F&amp;layout=standard&amp;show_faces=true&amp;width=500&amp;action=like&amp;font=segoe+ui&amp;colorscheme=light&amp;height=80\" scrolling=\"no\" frameborder=\"0\" style=\"border:none; overflow:hidden; width:500px; height:80px;\" allowTransparency=\"true\"><\/iframe><\/div>\n<!-- google_ad_section_end -->\n","protected":false},"excerpt":{"rendered":"<p>Taucha. Sieben Eheschlie&#223;ungen fanden gestern am bei Paaren offenbar beliebten magischen Datum, dem 8.8.08, statt. Jede war auf ihre Weise etwas Besonderes, dennoch stach eine heraus. Denn mit der Hochzeit von Kristie und Tom D&#246;hler aus Leipzig wurden eine Amerikanerin und ein Deutscher amtlich zu Mann und Frau erkl&#228;rt. Uta Schneider vom Tauchaer Standesamt war&#8230;<\/p>\n<p><a href=\"https:\/\/www.danielgrosse.com\/blog\/deutsch-amerikanische-trauung\/\"><span class=\"glyphicon glyphicon-arrow-right\"><\/span>&nbsp;Weiterlesen<\/a><\/p>","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-1240","post","type-post","status-publish","format-standard","hentry","category-lokales"],"_links":{"self":[{"href":"https:\/\/www.danielgrosse.com\/blog\/wp-json\/wp\/v2\/posts\/1240","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.danielgrosse.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.danielgrosse.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.danielgrosse.com\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.danielgrosse.com\/blog\/wp-json\/wp\/v2\/comments?post=1240"}],"version-history":[{"count":2,"href":"https:\/\/www.danielgrosse.com\/blog\/wp-json\/wp\/v2\/posts\/1240\/revisions"}],"predecessor-version":[{"id":1242,"href":"https:\/\/www.danielgrosse.com\/blog\/wp-json\/wp\/v2\/posts\/1240\/revisions\/1242"}],"wp:attachment":[{"href":"https:\/\/www.danielgrosse.com\/blog\/wp-json\/wp\/v2\/media?parent=1240"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.danielgrosse.com\/blog\/wp-json\/wp\/v2\/categories?post=1240"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.danielgrosse.com\/blog\/wp-json\/wp\/v2\/tags?post=1240"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}