{"id":330,"date":"2007-01-07T15:21:30","date_gmt":"2007-01-07T14:21:30","guid":{"rendered":"http:\/\/www.danielgrosse.com\/blog\/2007\/01\/07\/das-ist-keine-11-rechnung\/"},"modified":"2018-03-31T12:10:36","modified_gmt":"2018-03-31T10:10:36","slug":"das-ist-keine-11-rechnung","status":"publish","type":"post","link":"https:\/\/www.danielgrosse.com\/blog\/das-ist-keine-11-rechnung\/","title":{"rendered":"Das ist keine 1&#038;1&nbsp;Rechnung!"},"content":{"rendered":"\n<!-- google_ad_section_start -->\n<p>Ich bin nicht bei 1&#038;1. <strike>Auch radionews.de wird nicht dort gehosted<\/strike>. <strong>Update:<\/strong> Sorry. radionews l&#228;uft bei 1&#038;1. <strike>Darum<\/strike> Trotzdem ahnte ich, was das f&#252;r eine angebliche <a href=\"http:\/\/www.danielgrosse.com\/blog\/uploads\/1und1rechnung.jpg\">Rechnung<\/a> ist, die da soeben an eine Mail-Adresse f&#252;r radionews bei mir eintrudelte. Knappe 60 Euro f&#252;r den Monat Dezember. Die Rechnung h&#228;nge als PDF-EXE-Format an. Ein extra Programm sei nicht n&#246;tig zum Betrachten. Klar doch.<\/p>\n<p>Backdoor.Win32.Agent.akf nennt Kaspersky das, was er da sofort nach Speichern des Anhangs erkannte. Tolle Fernbedienung. Gel&#246;scht. Also: auuufpassen! Ein <a href=\"http:\/\/www.symantec.com\/security_response\/writeup.jsp?docid=2003-112112-1102-99\">Removal-Tool<\/a> f&#252;r die Ur-Form des Trojaners gibt es bei Symantec. Sollte auch f&#252;r den hier oben klappen.<\/p>\n<div id=\"facebook_like\"><iframe src=\"http:\/\/www.facebook.com\/plugins\/like.php?href=https%3A%2F%2Fwww.danielgrosse.com%2Fblog%2Fdas-ist-keine-11-rechnung%2F&amp;layout=standard&amp;show_faces=true&amp;width=500&amp;action=like&amp;font=segoe+ui&amp;colorscheme=light&amp;height=80\" scrolling=\"no\" frameborder=\"0\" style=\"border:none; overflow:hidden; width:500px; height:80px;\" allowTransparency=\"true\"><\/iframe><\/div>\n<!-- google_ad_section_end -->\n","protected":false},"excerpt":{"rendered":"<p>Ich bin nicht bei 1&#038;1. Auch radionews.de wird nicht dort gehosted. Update: Sorry. radionews l&#228;uft bei 1&#038;1. Darum Trotzdem ahnte ich, was das f&#252;r eine angebliche Rechnung ist, die da soeben an eine Mail-Adresse f&#252;r radionews bei mir eintrudelte. Knappe 60 Euro f&#252;r den Monat Dezember. Die Rechnung h&#228;nge als PDF-EXE-Format an. Ein extra Programm&#8230;<\/p>\n<p><a href=\"https:\/\/www.danielgrosse.com\/blog\/das-ist-keine-11-rechnung\/\"><span class=\"glyphicon glyphicon-arrow-right\"><\/span>&nbsp;Weiterlesen<\/a><\/p>","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,3,18],"tags":[],"class_list":["post-330","post","type-post","status-publish","format-standard","hentry","category-alltagliches","category-mediales","category-spam-macht-keinen-spas"],"_links":{"self":[{"href":"https:\/\/www.danielgrosse.com\/blog\/wp-json\/wp\/v2\/posts\/330","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.danielgrosse.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.danielgrosse.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.danielgrosse.com\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.danielgrosse.com\/blog\/wp-json\/wp\/v2\/comments?post=330"}],"version-history":[{"count":2,"href":"https:\/\/www.danielgrosse.com\/blog\/wp-json\/wp\/v2\/posts\/330\/revisions"}],"predecessor-version":[{"id":4452,"href":"https:\/\/www.danielgrosse.com\/blog\/wp-json\/wp\/v2\/posts\/330\/revisions\/4452"}],"wp:attachment":[{"href":"https:\/\/www.danielgrosse.com\/blog\/wp-json\/wp\/v2\/media?parent=330"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.danielgrosse.com\/blog\/wp-json\/wp\/v2\/categories?post=330"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.danielgrosse.com\/blog\/wp-json\/wp\/v2\/tags?post=330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}